{"id":805,"date":"2017-01-13T19:28:32","date_gmt":"2017-01-13T18:28:32","guid":{"rendered":"http:\/\/www.wonderpetasse.com\/?p=805"},"modified":"2021-11-02T17:38:56","modified_gmt":"2021-11-02T16:38:56","slug":"tartiflette-au-cookeo","status":"publish","type":"post","link":"https:\/\/www.wonderpetasse.com\/fr_fr\/tartiflette-au-cookeo\/","title":{"rendered":"Tartiflette au Cook\u00e9o"},"content":{"rendered":"\n<p>Il fait de plus en plus frais ces derniers jours : alors autant en profiter pour savourer un bon plat de saison, la Tartiflette au Cook\u00e9o !<\/p>\n\n\n\n<p>Avec le <strong><a href=\"https:\/\/amzn.to\/2ZV9DsJ\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Cook\u00e9o -click ici si par le plus grand des hasards tu ne connais pas &#8211; <\/a><\/strong> c&#8217;est bluffant de simplicit\u00e9 et de rapidit\u00e9.<\/p>\n\n\n\n<p>Bon ok, j&#8217;avoue, mon <a href=\"https:\/\/amzn.to\/3CDPEwX\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">\u00e9plucheur \u00e0 pommes &#8211; click ici &#8211;<\/a> me sert aussi \u00e0 \u00e9plucher mes pommes de terres en &#8230; 2 minutes ! Ca aide ! Concr\u00e8tement, avec l&#8217;\u00e9plucheur, on gagne bien&#8230;8 minutes, parce que le plus long \u00e0 r\u00e9aliser dans cette recette c&#8217;est de peler les pommes de terre !<\/p>\n\n\n\n<p>C&#8217;est un art d&#8217;\u00eatre une Wonderp\u00e9tasse, et je m&#8217;y applique chaque jour ! (nan, mais s\u00e9rieux, qui a le temps d&#8217;\u00e9plucher les patates ? j&#8217;fais pas le remake de Prison Break en cuisine mw\u00e2aaah !)<\/p>\n\n\n\n<p>Je l&#8217;aime tellement mon \u00e9plucheur m\u00e9canique, que je te montre son efficacit\u00e9 en\u00a0vid\u00e9o.<\/p>\n\n\n<div style=\"width: 750px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-805-1\" width=\"750\" height=\"422\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"http:\/\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/01\/01a16327e48f2b085338ae79ecac026ad02e27990c.mp4?_=1\" \/><a href=\"http:\/\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/01\/01a16327e48f2b085338ae79ecac026ad02e27990c.mp4\">http:\/\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/01\/01a16327e48f2b085338ae79ecac026ad02e27990c.mp4<\/a><\/video><\/div>\n\n\n\n<p>Et deux minutes apr\u00e8s : toutes les pommes de terre son \u00e9pluch\u00e9es ! C&#8217;est MA GI QUE !<\/p>\n\n\n\n<div class=\"wp-block-image is-style-default\"><figure class=\"aligncenter\"><a href=\"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/01\/IMG_4150.jpg\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"225\" data-attachment-id=\"818\" data-permalink=\"https:\/\/www.wonderpetasse.com\/fr_fr\/tartiflette-au-cookeo\/img_4150\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/01\/IMG_4150-e1484331994758.jpg?fit=3264%2C2448&amp;ssl=1\" data-orig-size=\"3264,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 6&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1484306326&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.15&quot;,&quot;iso&quot;:&quot;250&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;6&quot;}\" data-image-title=\"IMG_4150\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/01\/IMG_4150-e1484331994758.jpg?fit=750%2C563&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/01\/IMG_4150-e1484331994758-300x225.jpg?resize=300%2C225\" alt=\"Pommes de terre tartiflette\" class=\"wp-image-818\" srcset=\"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/01\/IMG_4150-e1484331994758.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/01\/IMG_4150-e1484331994758.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/01\/IMG_4150-e1484331994758.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/01\/IMG_4150-e1484331994758.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/01\/IMG_4150-e1484331994758.jpg?w=1500&amp;ssl=1 1500w, https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/01\/IMG_4150-e1484331994758.jpg?w=2250&amp;ssl=1 2250w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"text-decoration: underline;\">Ingr\u00e9dients :<\/span><\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li>1,200 kg de pommes de terre<\/li><li>20 cl de cr\u00e8me liquide (je prends toujours celle \u00e0 4%)<\/li><li>15 cl de vin blanc<\/li><li>1 oignon<\/li><li>2 gousses d\u2019ail<\/li><li>200 g de lardons<\/li><li>1 reblochon<\/li><li>sel<\/li><li>poivre<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"text-decoration: underline;\">Instructions :<\/span><\/h3>\n\n\n\n<ol class=\"wp-block-list\"><li>\u00c9plucher et couper les pommes de terre en rondelles.<\/li><li>En mode dorer : mettre les oignons avec les lardons.<\/li><li>Ajouter les pommes de terres, la cr\u00e8me, le vin blanc, l\u2019ail press\u00e9, le sel et le poivre.<\/li><li>Bien m\u00e9langer.<\/li><li>Couper le reblochon en morceau et l\u2019ajouter au reste des ingr\u00e9dients.<\/li><li>Lancer la cuisson rapide pour 13 min.<\/li><\/ol>\n\n\n\n<p>Bon app&#8217; au chaud !<\/p>\n\n\n\n<div class=\"jetpack_subscription_widget\"><h2 class=\"widgettitle\">Abonnez-vous \u00e0 ce blog par e-mail.<\/h2>\n\t\t\t<div class=\"wp-block-jetpack-subscriptions__container\">\n\t\t\t<form action=\"#\" method=\"post\" accept-charset=\"utf-8\" id=\"subscribe-blog-1\"\n\t\t\t\tdata-blog=\"120586092\"\n\t\t\t\tdata-post_access_level=\"everybody\" >\n\t\t\t\t\t\t\t\t\t<div id=\"subscribe-text\"><p>Saisissez votre adresse e-mail pour vous abonner \u00e0 ce blog et recevoir une notification de chaque nouvel article par e-mail.<\/p>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t<p id=\"subscribe-email\">\n\t\t\t\t\t\t<label id=\"jetpack-subscribe-label\"\n\t\t\t\t\t\t\tclass=\"screen-reader-text\"\n\t\t\t\t\t\t\tfor=\"subscribe-field-1\">\n\t\t\t\t\t\t\tAdresse e-mail\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<input type=\"email\" name=\"email\" autocomplete=\"email\" required=\"required\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tvalue=\"\"\n\t\t\t\t\t\t\tid=\"subscribe-field-1\"\n\t\t\t\t\t\t\tplaceholder=\"Adresse e-mail\"\n\t\t\t\t\t\t\/>\n\t\t\t\t\t<\/p>\n\n\t\t\t\t\t<p id=\"subscribe-submit\"\n\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t<input type=\"hidden\" name=\"action\" value=\"subscribe\"\/>\n\t\t\t\t\t\t<input type=\"hidden\" name=\"source\" value=\"https:\/\/www.wonderpetasse.com\/fr_fr\/wp-json\/wp\/v2\/posts\/805\"\/>\n\t\t\t\t\t\t<input type=\"hidden\" name=\"sub-type\" value=\"widget\"\/>\n\t\t\t\t\t\t<input type=\"hidden\" name=\"redirect_fragment\" value=\"subscribe-blog-1\"\/>\n\t\t\t\t\t\t<input type=\"hidden\" id=\"_wpnonce\" name=\"_wpnonce\" value=\"10ec457b7b\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/fr_fr\/wp-json\/wp\/v2\/posts\/805\" \/>\t\t\t\t\t\t<button type=\"submit\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"wp-block-button__link\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tstyle=\"margin: 0; margin-left: 0px;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\tname=\"jetpack_subscriptions_widget\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\tAbonnez-vous\t\t\t\t\t\t<\/button>\n\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n<\/div>\n\n\n\n<p class=\"has-text-align-justify has-very-light-gray-background-color has-background has-small-font-size\">La cuisine est un partage et je suis heureuse de partager mes recettes que je mets un temps \u2013 fou \u2013 \u00e0 publier sur le Blog. En effet, r\u00e9aliser la recette en s\u2019arr\u00eatant pour prendre la photo (ou cadrer pour la vid\u00e9o), se laver les mains, continuer la recette, uploader les photos, r\u00e9diger l\u2019article, r\u00e9aliser l\u2019harmonisation de la publication\u00a0: c\u2019est pratiquement une journ\u00e9e de boulot \u2013 non r\u00e9mun\u00e9r\u00e9. Tu peux partager cette recette o\u00f9 tu veux ; mais par \u00e9gard, pour le temps que je passe \u00e0 le faire \u2013 gratuitement- <strong>je te serai reconnaissante de partager l\u2019URL de cette page et non pas des screens.<\/strong><br><br>Partager des screens d\u2019une recette du Blog sur les r\u00e9seaux sociaux, c\u2019est comme si tu avais fait tout le m\u00e9nage chez toi et qu\u2019on te disait\u00a0: <em>\u00ab\u00a0cool, tu as nettoy\u00e9 les WC\u00a0!\u00a0\u00bb<\/em> alors que tu as pass\u00e9 la journ\u00e9e \u00e0 tout lessiver, tu vois\u00a0? Merci \u00e0 toi !<br><br><strong>Merci de ne pas publier ma recette sur l&#8217;application Cook\u00e9o : si je ne le fais pas c&#8217;est parce que je ne peux pas y inscrire tous mes conseils et astuces pour r\u00e9ussir la recette !<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une Tartiflette rapide faite au Cook\u00e9o<\/p>\n","protected":false},"author":1,"featured_media":830,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[249,39,6],"tags":[40,72,95,133],"class_list":["post-805","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recettes","category-recettes-cookeo","category-recettes-rapides","tag-cookeo","tag-lardons","tag-pommes-de-terre","tag-tartiflettes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tartiflette au Cook\u00e9o &#8902; La cuisine de Wonderp\u00e9tasse<\/title>\n<meta name=\"description\" content=\"Une tartiflette super rapide r\u00e9alis\u00e9e au Cookeo pour un plat gourmand et r\u00e9confort en un rien de temps en cuisine !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.wonderpetasse.com\/fr_fr\/tartiflette-au-cookeo\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tartiflette au Cook\u00e9o &#8902; La cuisine de Wonderp\u00e9tasse\" \/>\n<meta property=\"og:description\" content=\"Une tartiflette super rapide r\u00e9alis\u00e9e au Cookeo pour un plat gourmand et r\u00e9confort en un rien de temps en cuisine !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wonderpetasse.com\/fr_fr\/tartiflette-au-cookeo\/\" \/>\n<meta property=\"og:site_name\" content=\"La cuisine de Wonderp\u00e9tasse\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Wonderpetasse\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-13T18:28:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-02T16:38:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i2.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/01\/IMG_0115.jpg?fit=2049%2C1535&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"2049\" \/>\n\t<meta property=\"og:image:height\" content=\"1535\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Wonderp\u00e9tasse\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Wonderpetasse\" \/>\n<meta name=\"twitter:site\" content=\"@Wonderpetasse\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Wonderp\u00e9tasse\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.wonderpetasse.com\/tartiflette-au-cookeo\/\",\"url\":\"https:\/\/www.wonderpetasse.com\/tartiflette-au-cookeo\/\",\"name\":\"Tartiflette au Cook\u00e9o &#8902; La cuisine de Wonderp\u00e9tasse\",\"isPartOf\":{\"@id\":\"https:\/\/www.wonderpetasse.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.wonderpetasse.com\/tartiflette-au-cookeo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.wonderpetasse.com\/tartiflette-au-cookeo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/01\/IMG_0115.jpg?fit=2049%2C1535&ssl=1\",\"datePublished\":\"2017-01-13T18:28:32+00:00\",\"dateModified\":\"2021-11-02T16:38:56+00:00\",\"author\":{\"@id\":\"https:\/\/www.wonderpetasse.com\/#\/schema\/person\/cc429bda20091603cea6148e26de770b\"},\"description\":\"Une tartiflette super rapide r\u00e9alis\u00e9e au Cookeo pour un plat gourmand et r\u00e9confort en un rien de temps en cuisine !\",\"breadcrumb\":{\"@id\":\"https:\/\/www.wonderpetasse.com\/tartiflette-au-cookeo\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.wonderpetasse.com\/tartiflette-au-cookeo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.wonderpetasse.com\/tartiflette-au-cookeo\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/01\/IMG_0115.jpg?fit=2049%2C1535&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/01\/IMG_0115.jpg?fit=2049%2C1535&ssl=1\",\"width\":2049,\"height\":1535},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.wonderpetasse.com\/tartiflette-au-cookeo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.wonderpetasse.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tartiflette au Cook\u00e9o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.wonderpetasse.com\/#website\",\"url\":\"https:\/\/www.wonderpetasse.com\/\",\"name\":\"La cuisine de Wonderp\u00e9tasse\",\"description\":\"La cuisine, mon addiction !\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.wonderpetasse.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.wonderpetasse.com\/#\/schema\/person\/cc429bda20091603cea6148e26de770b\",\"name\":\"Wonderp\u00e9tasse\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.wonderpetasse.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/98fc9233c7447e5af5696aea625f16865d2b5bde56abf1686128819b2688149f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/98fc9233c7447e5af5696aea625f16865d2b5bde56abf1686128819b2688149f?s=96&d=mm&r=g\",\"caption\":\"Wonderp\u00e9tasse\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tartiflette au Cook\u00e9o &#8902; La cuisine de Wonderp\u00e9tasse","description":"Une tartiflette super rapide r\u00e9alis\u00e9e au Cookeo pour un plat gourmand et r\u00e9confort en un rien de temps en cuisine !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.wonderpetasse.com\/fr_fr\/tartiflette-au-cookeo\/","og_locale":"fr_FR","og_type":"article","og_title":"Tartiflette au Cook\u00e9o &#8902; La cuisine de Wonderp\u00e9tasse","og_description":"Une tartiflette super rapide r\u00e9alis\u00e9e au Cookeo pour un plat gourmand et r\u00e9confort en un rien de temps en cuisine !","og_url":"https:\/\/www.wonderpetasse.com\/fr_fr\/tartiflette-au-cookeo\/","og_site_name":"La cuisine de Wonderp\u00e9tasse","article_publisher":"https:\/\/www.facebook.com\/Wonderpetasse\/","article_published_time":"2017-01-13T18:28:32+00:00","article_modified_time":"2021-11-02T16:38:56+00:00","og_image":[{"width":2049,"height":1535,"url":"https:\/\/i2.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/01\/IMG_0115.jpg?fit=2049%2C1535&ssl=1","type":"image\/jpeg"}],"author":"Wonderp\u00e9tasse","twitter_card":"summary_large_image","twitter_creator":"@Wonderpetasse","twitter_site":"@Wonderpetasse","twitter_misc":{"\u00c9crit par":"Wonderp\u00e9tasse","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.wonderpetasse.com\/tartiflette-au-cookeo\/","url":"https:\/\/www.wonderpetasse.com\/tartiflette-au-cookeo\/","name":"Tartiflette au Cook\u00e9o &#8902; La cuisine de Wonderp\u00e9tasse","isPartOf":{"@id":"https:\/\/www.wonderpetasse.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.wonderpetasse.com\/tartiflette-au-cookeo\/#primaryimage"},"image":{"@id":"https:\/\/www.wonderpetasse.com\/tartiflette-au-cookeo\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/01\/IMG_0115.jpg?fit=2049%2C1535&ssl=1","datePublished":"2017-01-13T18:28:32+00:00","dateModified":"2021-11-02T16:38:56+00:00","author":{"@id":"https:\/\/www.wonderpetasse.com\/#\/schema\/person\/cc429bda20091603cea6148e26de770b"},"description":"Une tartiflette super rapide r\u00e9alis\u00e9e au Cookeo pour un plat gourmand et r\u00e9confort en un rien de temps en cuisine !","breadcrumb":{"@id":"https:\/\/www.wonderpetasse.com\/tartiflette-au-cookeo\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wonderpetasse.com\/tartiflette-au-cookeo\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.wonderpetasse.com\/tartiflette-au-cookeo\/#primaryimage","url":"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/01\/IMG_0115.jpg?fit=2049%2C1535&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/01\/IMG_0115.jpg?fit=2049%2C1535&ssl=1","width":2049,"height":1535},{"@type":"BreadcrumbList","@id":"https:\/\/www.wonderpetasse.com\/tartiflette-au-cookeo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.wonderpetasse.com\/"},{"@type":"ListItem","position":2,"name":"Tartiflette au Cook\u00e9o"}]},{"@type":"WebSite","@id":"https:\/\/www.wonderpetasse.com\/#website","url":"https:\/\/www.wonderpetasse.com\/","name":"La cuisine de Wonderp\u00e9tasse","description":"La cuisine, mon addiction !","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wonderpetasse.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.wonderpetasse.com\/#\/schema\/person\/cc429bda20091603cea6148e26de770b","name":"Wonderp\u00e9tasse","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.wonderpetasse.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/98fc9233c7447e5af5696aea625f16865d2b5bde56abf1686128819b2688149f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/98fc9233c7447e5af5696aea625f16865d2b5bde56abf1686128819b2688149f?s=96&d=mm&r=g","caption":"Wonderp\u00e9tasse"}}]}},"views":10509,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/01\/IMG_0115.jpg?fit=2049%2C1535&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p89XWY-cZ","jetpack-related-posts":[{"id":1707,"url":"https:\/\/www.wonderpetasse.com\/fr_fr\/poulet-lardons-a-facon\/","url_meta":{"origin":805,"position":0},"title":"Poulet aux lardons \u00e0 ma fa\u00e7on","author":"Wonderp\u00e9tasse","date":"9 juin 2017","format":false,"excerpt":"Poulet aux lardons ultra simple au Cook\u00e9o","rel":"","context":"Dans &quot;Recettes Cook\u00e9o&quot;","block_context":{"text":"Recettes Cook\u00e9o","link":"https:\/\/www.wonderpetasse.com\/fr_fr\/category\/recettes\/recettes-cookeo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/06\/IMG_5464.jpg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/06\/IMG_5464.jpg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/06\/IMG_5464.jpg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/06\/IMG_5464.jpg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/06\/IMG_5464.jpg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":1952,"url":"https:\/\/www.wonderpetasse.com\/fr_fr\/boulettes-de-boeuf-sauce-tomate-cookeo\/","url_meta":{"origin":805,"position":1},"title":"Boulettes de boeuf sauce tomate (au Cook\u00e9o ou pas)","author":"Wonderp\u00e9tasse","date":"10 juin 2017","format":false,"excerpt":"Bon, il faut le reconna\u00eetre, souvent j'ach\u00e8te de la viande hach\u00e9e chez mon formidable Boucher parce qu'elle est tellement belle, tellement fra\u00eeche que je visualise plein de plats sympathiques \u00e0 faire et puis, paaaf, tout d'un coup je me transforme en Kinder (la Kinder, c'est la nana qui est brune\u2026","rel":"","context":"Dans &quot;Recettes Cook\u00e9o&quot;","block_context":{"text":"Recettes Cook\u00e9o","link":"https:\/\/www.wonderpetasse.com\/fr_fr\/category\/recettes\/recettes-cookeo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/06\/IMG_5746.jpg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/06\/IMG_5746.jpg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/06\/IMG_5746.jpg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/06\/IMG_5746.jpg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/06\/IMG_5746.jpg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":4266,"url":"https:\/\/www.wonderpetasse.com\/fr_fr\/tagliatelles-carbonara-au-cookeo\/","url_meta":{"origin":805,"position":2},"title":"Ma version des Tagliatelles Carbonara au Cookeo","author":"Wonderp\u00e9tasse","date":"17 novembre 2019","format":false,"excerpt":"Ma Version des Tagliatelles Carbonara au Cookeo","rel":"","context":"Dans &quot;Recettes Cook\u00e9o&quot;","block_context":{"text":"Recettes Cook\u00e9o","link":"https:\/\/www.wonderpetasse.com\/fr_fr\/category\/recettes\/recettes-cookeo\/"},"img":{"alt_text":"Tagiliatelles Carbonara Wonderp\u00e9tasse","src":"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2019\/11\/img_3386.jpg?fit=745%2C563&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2019\/11\/img_3386.jpg?fit=745%2C563&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2019\/11\/img_3386.jpg?fit=745%2C563&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2019\/11\/img_3386.jpg?fit=745%2C563&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":760,"url":"https:\/\/www.wonderpetasse.com\/fr_fr\/ma-version-de-la-sauce-bolognaise\/","url_meta":{"origin":805,"position":3},"title":"Ma version de la sauce Bolognaise","author":"Wonderp\u00e9tasse","date":"11 janvier 2017","format":false,"excerpt":"Les spaghettis \u00e0 la sauce bolognaise, c'est un classique que tout le monde connait. Les variations pullulent sur le Net, avec ou sans vin rouge, avec coulis de tomates ou tomates concass\u00e9es etc... Ma version est celle de ma maman. \u00a0 Au Cook\u00e9o, elle se fait en 5 minutes. En\u2026","rel":"","context":"Dans &quot;Recettes Cook\u00e9o&quot;","block_context":{"text":"Recettes Cook\u00e9o","link":"https:\/\/www.wonderpetasse.com\/fr_fr\/category\/recettes\/recettes-cookeo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/01\/IMG_4137.jpg?fit=900%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/01\/IMG_4137.jpg?fit=900%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/01\/IMG_4137.jpg?fit=900%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/01\/IMG_4137.jpg?fit=900%2C1200&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":562,"url":"https:\/\/www.wonderpetasse.com\/fr_fr\/lentilles-aux-saucisses-cookeo\/","url_meta":{"origin":805,"position":4},"title":"Lentilles aux saucisses de Montb\u00e9liard au Cook\u00e9o","author":"Wonderp\u00e9tasse","date":"4 janvier 2017","format":false,"excerpt":"Un plat rapide et simple : les lentilles aux saucisses","rel":"","context":"Dans &quot;Recettes Cook\u00e9o&quot;","block_context":{"text":"Recettes Cook\u00e9o","link":"https:\/\/www.wonderpetasse.com\/fr_fr\/category\/recettes\/recettes-cookeo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/01\/IMG_4028.jpg?fit=900%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/01\/IMG_4028.jpg?fit=900%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/01\/IMG_4028.jpg?fit=900%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/01\/IMG_4028.jpg?fit=900%2C1200&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":521,"url":"https:\/\/www.wonderpetasse.com\/fr_fr\/crevettes-a-la-coriandre-et-ses-vermicelles-de-riz-au-cookeo\/","url_meta":{"origin":805,"position":5},"title":"Crevettes \u00e0 la Coriandre et ses vermicelles de riz au Cook\u00e9o","author":"Wonderp\u00e9tasse","date":"3 janvier 2017","format":false,"excerpt":"Une soupe de crevettes asiatique aux crevettes","rel":"","context":"Dans &quot;Recettes Cook\u00e9o&quot;","block_context":{"text":"Recettes Cook\u00e9o","link":"https:\/\/www.wonderpetasse.com\/fr_fr\/category\/recettes\/recettes-cookeo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/01\/IMG_4024.jpg?fit=720%2C960&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/01\/IMG_4024.jpg?fit=720%2C960&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/01\/IMG_4024.jpg?fit=720%2C960&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/01\/IMG_4024.jpg?fit=720%2C960&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.wonderpetasse.com\/fr_fr\/wp-json\/wp\/v2\/posts\/805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wonderpetasse.com\/fr_fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wonderpetasse.com\/fr_fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wonderpetasse.com\/fr_fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wonderpetasse.com\/fr_fr\/wp-json\/wp\/v2\/comments?post=805"}],"version-history":[{"count":23,"href":"https:\/\/www.wonderpetasse.com\/fr_fr\/wp-json\/wp\/v2\/posts\/805\/revisions"}],"predecessor-version":[{"id":6086,"href":"https:\/\/www.wonderpetasse.com\/fr_fr\/wp-json\/wp\/v2\/posts\/805\/revisions\/6086"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wonderpetasse.com\/fr_fr\/wp-json\/wp\/v2\/media\/830"}],"wp:attachment":[{"href":"https:\/\/www.wonderpetasse.com\/fr_fr\/wp-json\/wp\/v2\/media?parent=805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wonderpetasse.com\/fr_fr\/wp-json\/wp\/v2\/categories?post=805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wonderpetasse.com\/fr_fr\/wp-json\/wp\/v2\/tags?post=805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}