{"id":1452,"date":"2017-03-16T19:53:39","date_gmt":"2017-03-16T18:53:39","guid":{"rendered":"http:\/\/www.wonderpetasse.com\/la-meringue-suisse\/"},"modified":"2017-09-10T00:36:08","modified_gmt":"2017-09-09T22:36:08","slug":"la-meringue-suisse","status":"publish","type":"post","link":"https:\/\/www.wonderpetasse.com\/fr_fr\/la-meringue-suisse\/","title":{"rendered":"La Meringue Suisse"},"content":{"rendered":"<p>La Meringue Suisse est celle qu&#8217;on utilise pour l&#8217;omelette norv\u00e9gienne ou la tarte au citron meringu\u00e9e ou m\u00eame pour les petites d\u00e9corations tels que les champignons des b\u00fbches.<\/p>\n<p>Contrairement \u00e0 la Meringue fran\u00e7aise, elle prend moins l&#8217;humidit\u00e9 et se tient mieux plus longtemps.<\/p>\n<p>Elle est naturellement id\u00e9ale quand elle ne peut pas \u00eatre cuite comme par exemple lorsqu&#8217;elle doit seulement \u00eatre dor\u00e9e au grill du four ou au chalumeau.<\/p>\n<p>La recette se fait au bain marie pour la premi\u00e8re \u00e9tape et c&#8217;est ce qui permet la fonte compl\u00e8te du sucre.<\/p>\n<p><b><u>Ingr\u00e9dients<\/u><\/b> :<\/p>\n<p>Des blancs d&#8217;oeufs (pour moi 2 blancs dont le poids total est de 69 g)<\/p>\n<p>Le double du poids des blancs en sucre semoule (pour moi donc 138 g)<\/p>\n<p><b><u>Instructions<\/u><\/b> :<\/p>\n<p>Dans un r\u00e9cipient supportant la chaleur mettre les blancs et la totalit\u00e9 du sucre.<\/p>\n<p>Pour le bain marie :<\/p>\n<p>Mettre le r\u00e9cipient contenant le m\u00e9lange blancs\/sucre dans une casserole contenant de l&#8217;eau qui sera chauff\u00e9e en m\u00eame temps que vous fouettez au fouet \u00e0 main ou \u00e9lectrique (c&#8217;est moins fatiguant) le m\u00e9lange jusqu&#8217;\u00e0 la temp\u00e9rature de 45\u00b0C. Vous pouvez proc\u00e9der au doigt (la temp\u00e9rature doit \u00eatre juste au dessus de la temp\u00e9rature corporelle et donc supportable pour votre doigt) mais le mieux reste le thermom\u00e8tre de cuisine.<\/p>\n<p>Une fois la temp\u00e9rature atteinte, le sucre a fondu totalement et il faut battre au fouet \u00e9lectrique jusqu&#8217;\u00e0 complet refroidissement. Il faut compter un peu plus de 10 minutes (le bol doit \u00eatre froid).<br \/>\nOn dit que la Meringue est parfaite lorsque le fouet pr\u00e9sente ce fameux bec d&#8217;oiseau que l&#8217;on voit sur ma photo de la recette.<\/p>\n<p>Et voil\u00e0, simple non ?<br \/>\nIl ne reste plus qu&#8217;\u00e0 garnir votre tarte au citron ou \u00e0 dresser, gr\u00e2ce \u00e0 une poche \u00e0 douilles, pour en faire des meringues \u00e0 d\u00e9vorer pour les petites (ou grosses) fringales : la cuisson des Meringues se fait au four pr\u00e9chauff\u00e9 \u00e0 90\u00b0C pour 2 heures.<br \/>\n<a href=\"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/03\/img_0208.jpg\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" data-attachment-id=\"1475\" data-permalink=\"https:\/\/www.wonderpetasse.com\/fr_fr\/la-meringue-suisse\/img_0208\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/03\/img_0208.jpg?fit=2048%2C1536&amp;ssl=1\" data-orig-size=\"2048,1536\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"img_0208\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/03\/img_0208.jpg?fit=750%2C563&amp;ssl=1\" class=\"aligncenter size-medium wp-image-1475\" title=\"\" src=\"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/03\/img_0208.jpg?resize=480%2C360\" alt=\"\" width=\"480\" height=\"360\" srcset=\"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/03\/img_0208.jpg?w=2048&amp;ssl=1 2048w, https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/03\/img_0208.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/03\/img_0208.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/03\/img_0208.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/03\/img_0208.jpg?resize=400%2C300&amp;ssl=1 400w, https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/03\/img_0208.jpg?w=1500&amp;ssl=1 1500w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/a><\/p>\n<div class=\"jetpack_subscription_widget\"><h2 class=\"widgettitle\">Abonnez-vous \u00e0 ce blog par e-mail.<\/h2>\n\t\t\t<div class=\"wp-block-jetpack-subscriptions__container\">\n\t\t\t<form action=\"#\" method=\"post\" accept-charset=\"utf-8\" id=\"subscribe-blog-1\"\n\t\t\t\tdata-blog=\"120586092\"\n\t\t\t\tdata-post_access_level=\"everybody\" >\n\t\t\t\t\t\t\t\t\t<div id=\"subscribe-text\"><p>Saisissez votre adresse e-mail pour vous abonner \u00e0 ce blog et recevoir une notification de chaque nouvel article par e-mail.<\/p>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t<p id=\"subscribe-email\">\n\t\t\t\t\t\t<label id=\"jetpack-subscribe-label\"\n\t\t\t\t\t\t\tclass=\"screen-reader-text\"\n\t\t\t\t\t\t\tfor=\"subscribe-field-1\">\n\t\t\t\t\t\t\tAdresse e-mail\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<input type=\"email\" name=\"email\" autocomplete=\"email\" required=\"required\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tvalue=\"\"\n\t\t\t\t\t\t\tid=\"subscribe-field-1\"\n\t\t\t\t\t\t\tplaceholder=\"Adresse e-mail\"\n\t\t\t\t\t\t\/>\n\t\t\t\t\t<\/p>\n\n\t\t\t\t\t<p id=\"subscribe-submit\"\n\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t<input type=\"hidden\" name=\"action\" value=\"subscribe\"\/>\n\t\t\t\t\t\t<input type=\"hidden\" name=\"source\" value=\"https:\/\/www.wonderpetasse.com\/fr_fr\/wp-json\/wp\/v2\/posts\/1452\"\/>\n\t\t\t\t\t\t<input type=\"hidden\" name=\"sub-type\" value=\"widget\"\/>\n\t\t\t\t\t\t<input type=\"hidden\" name=\"redirect_fragment\" value=\"subscribe-blog-1\"\/>\n\t\t\t\t\t\t<input type=\"hidden\" id=\"_wpnonce\" name=\"_wpnonce\" value=\"10ec457b7b\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/fr_fr\/wp-json\/wp\/v2\/posts\/1452\" \/>\t\t\t\t\t\t<button type=\"submit\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tclass=\"wp-block-button__link\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tstyle=\"margin: 0; margin-left: 0px;\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\tname=\"jetpack_subscriptions_widget\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\tAbonnez-vous\t\t\t\t\t\t<\/button>\n\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La recette de la meringue Suisse<\/p>\n","protected":false},"author":1,"featured_media":1451,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5],"tags":[74],"class_list":["post-1452","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recettes-sucrees","tag-meringue-suisse"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Meringue Suisse &#8902; La cuisine de Wonderp\u00e9tasse<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.wonderpetasse.com\/fr_fr\/la-meringue-suisse\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Meringue Suisse &#8902; La cuisine de Wonderp\u00e9tasse\" \/>\n<meta property=\"og:description\" content=\"La recette de la meringue Suisse\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wonderpetasse.com\/fr_fr\/la-meringue-suisse\/\" \/>\n<meta property=\"og:site_name\" content=\"La cuisine de Wonderp\u00e9tasse\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Wonderpetasse\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-16T18:53:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-09T22:36:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/03\/img_0197-1.jpg?fit=1536%2C2048&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Wonderp\u00e9tasse\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Wonderpetasse\" \/>\n<meta name=\"twitter:site\" content=\"@Wonderpetasse\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Wonderp\u00e9tasse\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.wonderpetasse.com\/la-meringue-suisse\/\",\"url\":\"https:\/\/www.wonderpetasse.com\/la-meringue-suisse\/\",\"name\":\"La Meringue Suisse &#8902; La cuisine de Wonderp\u00e9tasse\",\"isPartOf\":{\"@id\":\"https:\/\/www.wonderpetasse.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.wonderpetasse.com\/la-meringue-suisse\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.wonderpetasse.com\/la-meringue-suisse\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/03\/img_0197-1.jpg?fit=1536%2C2048&ssl=1\",\"datePublished\":\"2017-03-16T18:53:39+00:00\",\"dateModified\":\"2017-09-09T22:36:08+00:00\",\"author\":{\"@id\":\"https:\/\/www.wonderpetasse.com\/#\/schema\/person\/cc429bda20091603cea6148e26de770b\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.wonderpetasse.com\/la-meringue-suisse\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.wonderpetasse.com\/la-meringue-suisse\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.wonderpetasse.com\/la-meringue-suisse\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/03\/img_0197-1.jpg?fit=1536%2C2048&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/03\/img_0197-1.jpg?fit=1536%2C2048&ssl=1\",\"width\":1536,\"height\":2048},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.wonderpetasse.com\/la-meringue-suisse\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.wonderpetasse.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Meringue Suisse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.wonderpetasse.com\/#website\",\"url\":\"https:\/\/www.wonderpetasse.com\/\",\"name\":\"La cuisine de Wonderp\u00e9tasse\",\"description\":\"La cuisine, mon addiction !\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.wonderpetasse.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.wonderpetasse.com\/#\/schema\/person\/cc429bda20091603cea6148e26de770b\",\"name\":\"Wonderp\u00e9tasse\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.wonderpetasse.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/98fc9233c7447e5af5696aea625f16865d2b5bde56abf1686128819b2688149f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/98fc9233c7447e5af5696aea625f16865d2b5bde56abf1686128819b2688149f?s=96&d=mm&r=g\",\"caption\":\"Wonderp\u00e9tasse\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Meringue Suisse &#8902; La cuisine de Wonderp\u00e9tasse","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.wonderpetasse.com\/fr_fr\/la-meringue-suisse\/","og_locale":"fr_FR","og_type":"article","og_title":"La Meringue Suisse &#8902; La cuisine de Wonderp\u00e9tasse","og_description":"La recette de la meringue Suisse","og_url":"https:\/\/www.wonderpetasse.com\/fr_fr\/la-meringue-suisse\/","og_site_name":"La cuisine de Wonderp\u00e9tasse","article_publisher":"https:\/\/www.facebook.com\/Wonderpetasse\/","article_published_time":"2017-03-16T18:53:39+00:00","article_modified_time":"2017-09-09T22:36:08+00:00","og_image":[{"width":1536,"height":2048,"url":"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/03\/img_0197-1.jpg?fit=1536%2C2048&ssl=1","type":"image\/jpeg"}],"author":"Wonderp\u00e9tasse","twitter_card":"summary_large_image","twitter_creator":"@Wonderpetasse","twitter_site":"@Wonderpetasse","twitter_misc":{"\u00c9crit par":"Wonderp\u00e9tasse","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.wonderpetasse.com\/la-meringue-suisse\/","url":"https:\/\/www.wonderpetasse.com\/la-meringue-suisse\/","name":"La Meringue Suisse &#8902; La cuisine de Wonderp\u00e9tasse","isPartOf":{"@id":"https:\/\/www.wonderpetasse.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.wonderpetasse.com\/la-meringue-suisse\/#primaryimage"},"image":{"@id":"https:\/\/www.wonderpetasse.com\/la-meringue-suisse\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/03\/img_0197-1.jpg?fit=1536%2C2048&ssl=1","datePublished":"2017-03-16T18:53:39+00:00","dateModified":"2017-09-09T22:36:08+00:00","author":{"@id":"https:\/\/www.wonderpetasse.com\/#\/schema\/person\/cc429bda20091603cea6148e26de770b"},"breadcrumb":{"@id":"https:\/\/www.wonderpetasse.com\/la-meringue-suisse\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wonderpetasse.com\/la-meringue-suisse\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.wonderpetasse.com\/la-meringue-suisse\/#primaryimage","url":"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/03\/img_0197-1.jpg?fit=1536%2C2048&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/03\/img_0197-1.jpg?fit=1536%2C2048&ssl=1","width":1536,"height":2048},{"@type":"BreadcrumbList","@id":"https:\/\/www.wonderpetasse.com\/la-meringue-suisse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.wonderpetasse.com\/"},{"@type":"ListItem","position":2,"name":"La Meringue Suisse"}]},{"@type":"WebSite","@id":"https:\/\/www.wonderpetasse.com\/#website","url":"https:\/\/www.wonderpetasse.com\/","name":"La cuisine de Wonderp\u00e9tasse","description":"La cuisine, mon addiction !","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wonderpetasse.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.wonderpetasse.com\/#\/schema\/person\/cc429bda20091603cea6148e26de770b","name":"Wonderp\u00e9tasse","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.wonderpetasse.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/98fc9233c7447e5af5696aea625f16865d2b5bde56abf1686128819b2688149f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/98fc9233c7447e5af5696aea625f16865d2b5bde56abf1686128819b2688149f?s=96&d=mm&r=g","caption":"Wonderp\u00e9tasse"}}]}},"views":5149,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/03\/img_0197-1.jpg?fit=1536%2C2048&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p89XWY-nq","jetpack-related-posts":[{"id":4442,"url":"https:\/\/www.wonderpetasse.com\/fr_fr\/tartelettes-au-citron-meringue-suisse\/","url_meta":{"origin":1452,"position":0},"title":"Tartelettes au citron Meringue Suisse","author":"Wonderp\u00e9tasse","date":"1 janvier 2020","format":false,"excerpt":"Des tartelettes au citron Meringue Suisse d\u00e9licieuses avec ou sans le Cake Factory, avec ou sans le Companion !","rel":"","context":"Dans &quot;Recettes au Cake Factory&quot;","block_context":{"text":"Recettes au Cake Factory","link":"https:\/\/www.wonderpetasse.com\/fr_fr\/category\/recettes\/recettes-au-cake-factory\/"},"img":{"alt_text":"Tartelette au citron Wonderp\u00e9tasse","src":"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2020\/01\/Tartelette-au-citron-meringue.jpg?fit=717%2C717&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2020\/01\/Tartelette-au-citron-meringue.jpg?fit=717%2C717&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2020\/01\/Tartelette-au-citron-meringue.jpg?fit=717%2C717&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2020\/01\/Tartelette-au-citron-meringue.jpg?fit=717%2C717&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":3481,"url":"https:\/\/www.wonderpetasse.com\/fr_fr\/tarte-au-citron-insert-meringue\/","url_meta":{"origin":1452,"position":1},"title":"Tarte au citron insert Meringue Suisse &#8211; avec ou sans Companion &#8211;","author":"Wonderp\u00e9tasse","date":"6 octobre 2018","format":false,"excerpt":"Une tarte au citron avec un insert Meringue Suisse","rel":"","context":"Dans &quot;Recettes au Companion&quot;","block_context":{"text":"Recettes au Companion","link":"https:\/\/www.wonderpetasse.com\/fr_fr\/category\/recettes\/recettes-au-companion\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2018\/10\/78AA7864-33D3-42D6-955A-38C6F079E1A4.jpeg?fit=900%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2018\/10\/78AA7864-33D3-42D6-955A-38C6F079E1A4.jpeg?fit=900%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2018\/10\/78AA7864-33D3-42D6-955A-38C6F079E1A4.jpeg?fit=900%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2018\/10\/78AA7864-33D3-42D6-955A-38C6F079E1A4.jpeg?fit=900%2C1200&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":1596,"url":"https:\/\/www.wonderpetasse.com\/fr_fr\/la-tarte-au-citron-meringuee-damier\/","url_meta":{"origin":1452,"position":2},"title":"\u00a0La tarte au citron meringu\u00e9e &#8220;damier&#8221; ou le g\u00e2teau qui m&#8217;a fait acc\u00e9der \u00e0 l&#8217;\u00e9mission concours LES ROIS DU GATEAU cet \u00e9t\u00e9 2017 !","author":"Wonderp\u00e9tasse","date":"14 avril 2017","format":false,"excerpt":"La recette du G\u00e2teau qui m'a permis de concourir \u00e0 l'\u00e9mission du Chef LIGNAC, \"Les Rois du G\u00e2teau\" en ao\u00fbt 2017 !","rel":"","context":"Dans &quot;Recettes au Companion&quot;","block_context":{"text":"Recettes au Companion","link":"https:\/\/www.wonderpetasse.com\/fr_fr\/category\/recettes\/recettes-au-companion\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/04\/img_2266.jpg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/04\/img_2266.jpg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/04\/img_2266.jpg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/04\/img_2266.jpg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2017\/04\/img_2266.jpg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":4724,"url":"https:\/\/www.wonderpetasse.com\/fr_fr\/meringue-francaise-bicolore\/","url_meta":{"origin":1452,"position":3},"title":"Meringue fran\u00e7aise bicolore","author":"Wonderp\u00e9tasse","date":"8 f\u00e9vrier 2020","format":false,"excerpt":"Une meringue fran\u00e7aise bicolore pour le plaisir, pour d\u00e9corer un g\u00e2teau ou pour une id\u00e9e de Saint Valentin : super simple !","rel":"","context":"Dans &quot;Recettes au Cake Factory&quot;","block_context":{"text":"Recettes au Cake Factory","link":"https:\/\/www.wonderpetasse.com\/fr_fr\/category\/recettes\/recettes-au-cake-factory\/"},"img":{"alt_text":"Meringue fran\u00e7aise bicolore Wonderp\u00e9tasse","src":"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2020\/02\/img_5811.jpg?fit=360%2C480&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":3522,"url":"https:\/\/www.wonderpetasse.com\/fr_fr\/smbc-creme-au-beurre-meringue-suisse-au-companion\/","url_meta":{"origin":1452,"position":4},"title":"SMBC ou Cr\u00e8me au beurre Meringue Suisse au Companion","author":"Wonderp\u00e9tasse","date":"21 octobre 2018","format":false,"excerpt":"La recette de la Cr\u00e8me au beurre Meringue Suisse au Companion ou SMBC, l\u00e9g\u00e8re et d\u00e9licieux","rel":"","context":"Dans &quot;Recettes au Companion&quot;","block_context":{"text":"Recettes au Companion","link":"https:\/\/www.wonderpetasse.com\/fr_fr\/category\/recettes\/recettes-au-companion\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2018\/10\/img_8347.jpg?fit=742%2C540&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2018\/10\/img_8347.jpg?fit=742%2C540&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2018\/10\/img_8347.jpg?fit=742%2C540&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2018\/10\/img_8347.jpg?fit=742%2C540&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":33,"url":"https:\/\/www.wonderpetasse.com\/fr_fr\/la-tarte-au-citron-comme-vincent-guerlais\/","url_meta":{"origin":1452,"position":5},"title":"La tarte au citron comme Vincent GUERLAIS au Companion","author":"Wonderp\u00e9tasse","date":"20 novembre 2016","format":false,"excerpt":"Cette recette est tir\u00e9e du blog de Mercotte et a \u00e9t\u00e9 r\u00e9alis\u00e9e \u00e0 l'aide de mon fid\u00e8le commis de cuisine, le Companion. Ingr\u00e9dients : Pour les d\u00f4mes de citron: 85 g de jus de citron jaune 85 g de jus de citron vert 2 \u0153ufs entiers 4 jaunes d\u2019\u0153ufs 80\u2026","rel":"","context":"Dans &quot;Recettes au Companion&quot;","block_context":{"text":"Recettes au Companion","link":"https:\/\/www.wonderpetasse.com\/fr_fr\/category\/recettes\/recettes-au-companion\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.wonderpetasse.com\/wp-content\/uploads\/2016\/11\/cropped-20161028_144738000_iOS.jpg?fit=512%2C512&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.wonderpetasse.com\/fr_fr\/wp-json\/wp\/v2\/posts\/1452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wonderpetasse.com\/fr_fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wonderpetasse.com\/fr_fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wonderpetasse.com\/fr_fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wonderpetasse.com\/fr_fr\/wp-json\/wp\/v2\/comments?post=1452"}],"version-history":[{"count":4,"href":"https:\/\/www.wonderpetasse.com\/fr_fr\/wp-json\/wp\/v2\/posts\/1452\/revisions"}],"predecessor-version":[{"id":2408,"href":"https:\/\/www.wonderpetasse.com\/fr_fr\/wp-json\/wp\/v2\/posts\/1452\/revisions\/2408"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wonderpetasse.com\/fr_fr\/wp-json\/wp\/v2\/media\/1451"}],"wp:attachment":[{"href":"https:\/\/www.wonderpetasse.com\/fr_fr\/wp-json\/wp\/v2\/media?parent=1452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wonderpetasse.com\/fr_fr\/wp-json\/wp\/v2\/categories?post=1452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wonderpetasse.com\/fr_fr\/wp-json\/wp\/v2\/tags?post=1452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}